{"id":265,"count":24,"description":"Todo lo que un People Leader necesita para <strong>mejorar el desarrollo de las personas<\/strong>.","link":"https:\/\/nailted.com\/blog\/es\/tag\/desarrollo-de-personas\/","name":"Desarrollo de personas","slug":"desarrollo-de-personas","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El mejor contenido sobre Desarrollo de personas -<\/title>\n<meta name=\"description\" content=\"Descubre todo lo que un People Leader necesita para mejorar el desarrollo de las personas.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El mejor contenido sobre Desarrollo de personas -\" \/>\n<meta property=\"og:description\" content=\"Descubre todo lo que un People Leader necesita para mejorar el desarrollo de las personas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nailted.com\/blog\/es\/tag\/desarrollo-de-personas\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@_nailted\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/nailted.com\/blog\/es\/tag\/desarrollo-de-personas\/\",\"url\":\"https:\/\/nailted.com\/blog\/es\/tag\/desarrollo-de-personas\/\",\"name\":\"El mejor contenido sobre Desarrollo de personas -\",\"isPartOf\":{\"@id\":\"https:\/\/nailted.com\/blog\/#website\"},\"description\":\"Descubre todo lo que un People Leader necesita para mejorar el desarrollo de las personas.\",\"inLanguage\":\"es\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nailted.com\/blog\/#website\",\"url\":\"https:\/\/nailted.com\/blog\/\",\"name\":\"Nailted Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/nailted.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nailted.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nailted.com\/blog\/#organization\",\"name\":\"Nailted Blog\",\"url\":\"https:\/\/nailted.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/nailted.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nailted.com\/blog\/wp-content\/uploads\/2020\/04\/blue@3x.svg\",\"contentUrl\":\"https:\/\/nailted.com\/blog\/wp-content\/uploads\/2020\/04\/blue@3x.svg\",\"width\":125,\"height\":31,\"caption\":\"Nailted Blog\"},\"image\":{\"@id\":\"https:\/\/nailted.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/nailted\/\",\"https:\/\/twitter.com\/_nailted\",\"https:\/\/www.linkedin.com\/company\/nailted\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El mejor contenido sobre Desarrollo de personas -","description":"Descubre todo lo que un People Leader necesita para mejorar el desarrollo de las personas.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"El mejor contenido sobre Desarrollo de personas -","og_description":"Descubre todo lo que un People Leader necesita para mejorar el desarrollo de las personas.","og_url":"https:\/\/nailted.com\/blog\/es\/tag\/desarrollo-de-personas\/","twitter_card":"summary_large_image","twitter_site":"@_nailted","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/nailted.com\/blog\/es\/tag\/desarrollo-de-personas\/","url":"https:\/\/nailted.com\/blog\/es\/tag\/desarrollo-de-personas\/","name":"El mejor contenido sobre Desarrollo de personas -","isPartOf":{"@id":"https:\/\/nailted.com\/blog\/#website"},"description":"Descubre todo lo que un People Leader necesita para mejorar el desarrollo de las personas.","inLanguage":"es"},{"@type":"WebSite","@id":"https:\/\/nailted.com\/blog\/#website","url":"https:\/\/nailted.com\/blog\/","name":"Nailted Blog","description":"","publisher":{"@id":"https:\/\/nailted.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nailted.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nailted.com\/blog\/#organization","name":"Nailted Blog","url":"https:\/\/nailted.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nailted.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/nailted.com\/blog\/wp-content\/uploads\/2020\/04\/blue@3x.svg","contentUrl":"https:\/\/nailted.com\/blog\/wp-content\/uploads\/2020\/04\/blue@3x.svg","width":125,"height":31,"caption":"Nailted Blog"},"image":{"@id":"https:\/\/nailted.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nailted\/","https:\/\/twitter.com\/_nailted","https:\/\/www.linkedin.com\/company\/nailted\/"]}]}},"_links":{"self":[{"href":"https:\/\/nailted.com\/blog\/wp-json\/wp\/v2\/tags\/265"}],"collection":[{"href":"https:\/\/nailted.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/nailted.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/nailted.com\/blog\/wp-json\/wp\/v2\/posts?tags=265"},{"href":"https:\/\/nailted.com\/blog\/wp-json\/wp\/v2\/podcast?tags=265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}