{"id":291,"count":3,"description":"Entrevistas a expertos en People &amp; Culture sobre la <strong>cultura de empresa, la experiencia del empleado y mucho m\u00e1s<\/strong>.","link":"https:\/\/nailted.com\/blog\/es\/tag\/entrevista\/","name":"Entrevista","slug":"entrevista","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las mejores entrevistas a expertos en People &amp; Culture<\/title>\n<meta name=\"description\" content=\"Descubre las mejores entrevistas a expertos en People &amp; Culture sobre la cultura de empresa, la experiencia del empleado y mucho m\u00e1s.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las mejores entrevistas a expertos en People &amp; Culture\" \/>\n<meta property=\"og:description\" content=\"Descubre las mejores entrevistas a expertos en People &amp; Culture sobre la cultura de empresa, la experiencia del empleado y mucho m\u00e1s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nailted.com\/blog\/es\/tag\/entrevista\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@_nailted\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/nailted.com\/blog\/es\/tag\/entrevista\/\",\"url\":\"https:\/\/nailted.com\/blog\/es\/tag\/entrevista\/\",\"name\":\"Las mejores entrevistas a expertos en People & Culture\",\"isPartOf\":{\"@id\":\"https:\/\/nailted.com\/blog\/#website\"},\"description\":\"Descubre las mejores entrevistas a expertos en People & Culture sobre la cultura de empresa, la experiencia del empleado y mucho m\u00e1s.\",\"inLanguage\":\"es\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nailted.com\/blog\/#website\",\"url\":\"https:\/\/nailted.com\/blog\/\",\"name\":\"Nailted Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/nailted.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nailted.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nailted.com\/blog\/#organization\",\"name\":\"Nailted Blog\",\"url\":\"https:\/\/nailted.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/nailted.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nailted.com\/blog\/wp-content\/uploads\/2020\/04\/blue@3x.svg\",\"contentUrl\":\"https:\/\/nailted.com\/blog\/wp-content\/uploads\/2020\/04\/blue@3x.svg\",\"width\":125,\"height\":31,\"caption\":\"Nailted Blog\"},\"image\":{\"@id\":\"https:\/\/nailted.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/nailted\/\",\"https:\/\/twitter.com\/_nailted\",\"https:\/\/www.linkedin.com\/company\/nailted\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las mejores entrevistas a expertos en People & Culture","description":"Descubre las mejores entrevistas a expertos en People & Culture sobre la cultura de empresa, la experiencia del empleado y mucho m\u00e1s.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Las mejores entrevistas a expertos en People & Culture","og_description":"Descubre las mejores entrevistas a expertos en People & Culture sobre la cultura de empresa, la experiencia del empleado y mucho m\u00e1s.","og_url":"https:\/\/nailted.com\/blog\/es\/tag\/entrevista\/","twitter_card":"summary_large_image","twitter_site":"@_nailted","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/nailted.com\/blog\/es\/tag\/entrevista\/","url":"https:\/\/nailted.com\/blog\/es\/tag\/entrevista\/","name":"Las mejores entrevistas a expertos en People & Culture","isPartOf":{"@id":"https:\/\/nailted.com\/blog\/#website"},"description":"Descubre las mejores entrevistas a expertos en People & Culture sobre la cultura de empresa, la experiencia del empleado y mucho m\u00e1s.","inLanguage":"es"},{"@type":"WebSite","@id":"https:\/\/nailted.com\/blog\/#website","url":"https:\/\/nailted.com\/blog\/","name":"Nailted Blog","description":"","publisher":{"@id":"https:\/\/nailted.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nailted.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nailted.com\/blog\/#organization","name":"Nailted Blog","url":"https:\/\/nailted.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nailted.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/nailted.com\/blog\/wp-content\/uploads\/2020\/04\/blue@3x.svg","contentUrl":"https:\/\/nailted.com\/blog\/wp-content\/uploads\/2020\/04\/blue@3x.svg","width":125,"height":31,"caption":"Nailted Blog"},"image":{"@id":"https:\/\/nailted.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nailted\/","https:\/\/twitter.com\/_nailted","https:\/\/www.linkedin.com\/company\/nailted\/"]}]}},"_links":{"self":[{"href":"https:\/\/nailted.com\/blog\/wp-json\/wp\/v2\/tags\/291"}],"collection":[{"href":"https:\/\/nailted.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/nailted.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/nailted.com\/blog\/wp-json\/wp\/v2\/posts?tags=291"},{"href":"https:\/\/nailted.com\/blog\/wp-json\/wp\/v2\/podcast?tags=291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}